    
 {"id":5457,"date":"2025-09-24T09:02:15","date_gmt":"2025-09-24T07:02:15","guid":{"rendered":"https:\/\/web-dev-weissblau.de\/microconsult\/?page_id=5457"},"modified":"2026-06-17T08:25:37","modified_gmt":"2026-06-17T06:25:37","slug":"data-protection","status":"publish","type":"page","link":"https:\/\/www.microconsult.de\/en\/datenschutz\/","title":{"rendered":"Privacy Notice"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; custom_padding_last_edited=&#8220;off|desktop&#8220; module_class=&#8220;top-blue-bar-heading-section&#8220; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#009cbc&#8220; background_image=&#8220;https:\/\/www.microconsult.de\/wp-content\/uploads\/2025\/04\/stage_about.png&#8220; max_width=&#8220;1600px&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;15px||15px||true|false&#8220; custom_padding_tablet=&#8220;100px||180px||false|false&#8220; custom_padding_phone=&#8220;50px||30px||false|false&#8220; background_last_edited=&#8220;on|tablet&#8220; use_background_color_gradient_tablet=&#8220;on&#8220; background_color_gradient_repeat_tablet=&#8220;off&#8220; background_color_gradient_stops_tablet=&#8220;rgba(0,0,0,0.25) 0%|rgba(0,0,0,0.25) 100%&#8220; background_color_gradient_overlays_image_tablet=&#8220;on&#8220; background_position_phone=&#8220;center_right&#8220; background_horizontal_offset_phone=&#8220;38%&#8220; border_radii=&#8220;on|10px|10px|10px|10px&#8220; border_radii_tablet=&#8220;on|0px|0px|0px|0px&#8220; border_radii_phone=&#8220;on|0px|0px|0px|0px&#8220; border_radii_last_edited=&#8220;on|tablet&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; width_tablet=&#8220;100%&#8220; width_phone=&#8220;80%&#8220; width_last_edited=&#8220;on|tablet&#8220; min_height=&#8220;260px&#8220; min_height_tablet=&#8220;260px&#8220; min_height_phone=&#8220;200px&#8220; min_height_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;0px|30px|0px|30px|true|true&#8220; custom_padding_tablet=&#8220;0px|30px|0px|30px|false|true&#8220; custom_padding_phone=&#8220;0px|0px|0px|0px|true|true&#8220; custom_css_main_element=&#8220;display:flex;||align-items:center;||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; custom_css_main_element=&#8220;margin-bottom:0px!important;&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text module_class=&#8220;blue-bar-heading&#8220; _builder_version=&#8220;4.25.0&#8243; text_font=&#8220;|600|||||||&#8220; text_font_size=&#8220;15px&#8220; text_line_height=&#8220;1.8em&#8220; header_font=&#8220;Raleway|700|||||||&#8220; header_font_size=&#8220;45px&#8220; header_line_height=&#8220;1.2em&#8220; background_layout=&#8220;dark&#8220; max_width=&#8220;800px&#8220; max_width_tablet=&#8220;&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|phone&#8220; custom_margin=&#8220;-10px||0px||false|false&#8220; custom_margin_tablet=&#8220;-10px||||false|false&#8220; custom_margin_phone=&#8220;0px||||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; animation_style=&#8220;fade&#8220; animation_direction=&#8220;top&#8220; text_font_size_tablet=&#8220;14px&#8220; text_font_size_phone=&#8220;&#8220; text_font_size_last_edited=&#8220;on|phone&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;32px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; custom_css_free_form=&#8220;@media(max-width:438px) and (min-width:350px){|| selector h1{|| font-size: clamp(1.5rem, -0.2401rem + 7.9545vw, 1.9375rem)!important;|| }||}&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1>Datenschutz<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;49px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; max_width=&#8220;1400px&#8220; module_alignment=&#8220;center&#8220; custom_padding=&#8220;||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row custom_padding_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; width_tablet=&#8220;100%&#8220; width_phone=&#8220;80%&#8220; width_last_edited=&#8220;on|phone&#8220; custom_padding=&#8220;|30px||30px|false|true&#8220; custom_padding_tablet=&#8220;|30px||30px|false|true&#8220; custom_padding_phone=&#8220;|0px||0px|false|true&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.25.0&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;Raleway||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;15px&#8220; link_text_color=&#8220;#b71278&#8243; header_2_font=&#8220;Raleway|700|||||||&#8220; header_2_text_color=&#8220;#1d1d1b&#8220; header_2_font_size=&#8220;28px&#8220; header_2_line_height=&#8220;1.2em&#8220; header_3_font=&#8220;Raleway|700|||||||&#8220; header_3_text_color=&#8220;#1d1d1b&#8220; header_3_font_size=&#8220;25px&#8220; header_3_line_height=&#8220;1.2em&#8220; header_4_font=&#8220;Raleway|700|||||||&#8220; header_4_text_color=&#8220;#1d1d1b&#8220; header_4_font_size=&#8220;19px&#8220; header_4_line_height=&#8220;1.2em&#8220; header_5_font=&#8220;Raleway|700|||||||&#8220; header_5_text_color=&#8220;#1d1d1b&#8220; header_5_font_size=&#8220;19px&#8220; header_5_line_height=&#8220;1.2em&#8220; header_6_font=&#8220;Raleway|700|||||||&#8220; header_6_text_color=&#8220;#1d1d1b&#8220; header_6_font_size=&#8220;16px&#8220; header_6_line_height=&#8220;1.2em&#8220; custom_padding=&#8220;||||false|true&#8220; header_2_font_size_tablet=&#8220;28px&#8220; header_2_font_size_phone=&#8220;26px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; header_3_font_size_tablet=&#8220;25px&#8220; header_3_font_size_phone=&#8220;24px&#8220; header_3_font_size_last_edited=&#8220;on|desktop&#8220; header_4_font_size_tablet=&#8220;18px&#8220; header_4_font_size_phone=&#8220;18px&#8220; header_4_font_size_last_edited=&#8220;on|desktop&#8220; header_5_font_size_tablet=&#8220;19px&#8220; header_5_font_size_phone=&#8220;20px&#8220; header_5_font_size_last_edited=&#8220;on|desktop&#8220; header_6_font_size_tablet=&#8220;16px&#8220; header_6_font_size_phone=&#8220;18px&#8220; header_6_font_size_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2>Datenschutzerkl\u00e4rung der MicroConsult Academy GmbH<\/h2>\n<p>Der Schutz Ihrer personenbezogenen Daten, die von uns beim Besuch unserer Webseite, unserer Trainings oder bei der Nutzung unseres Newsletters erhoben, verarbeitet und gespeichert werden, ist uns schon immer ein besonderes Anliegen.<\/p>\n<h3>1. Verantwortlich f\u00fcr Datenerfassung, -verarbeitung und -speicherung<\/h3>\n<p>MicroConsult Academy GmbH<br \/>Charles-de-Gaulle-Str. 6<br \/>81737 M\u00fcnchen<br \/>Tel.: 089 45061-71<br \/>Fax: 089 450617-17<br \/>Email: <a href=\"mailto:kontakt@microconsult.com\">kontakt@microconsult.com<\/a><\/p>\n<h3>2. Personenbezogene Daten<\/h3>\n<p>Personenbezogene Daten sind Einzelangaben, die eine Person direkt oder indirekt identifizieren k\u00f6nnen, wie z.B. Namen oder Adressen. In den hier beschriebenen Situationen k\u00f6nnen Daten von Ihnen automatisch erfasst, verarbeitet und gespeichert werden:<\/p>\n<h4>2a. Log-Dateien des Webservers<\/h4>\n<p>Diese Daten werden beim Besuch unserer Website durch unsere Webserver maschinell erfasst:<\/p>\n<ul>\n<li>die IP-Adresse, von der aus Sie unsere Seiten abrufen<\/li>\n<li>Datum und Uhrzeit des Abrufs<\/li>\n<li>aufgerufene Webseiten<\/li>\n<li>\u00fcbertragene Datenmenge (Byteanzahl)<\/li>\n<li>die Seite, von der aus die betrachtete Webseite angefordert wurde<\/li>\n<li>eine Beschreibung des verwendeten Webbrowsers<\/li>\n<\/ul>\n<p>Die beiden letztgenannten Datens\u00e4tze speichern die Webserver nur, falls sie von Ihrem Browserprogramm unaufgefordert \u00fcbermittelt werden.<\/p>\n<p>Diese Daten k\u00f6nnen wir nicht einzelnen Personen zuordnen. Eine Zusammenf\u00fchrung dieser Daten mit Informationen aus anderen Datenquellen findet nicht statt. Diese Protokolldaten dienen ausschlie\u00dflich zur technischen \u00dcberwachung des Serverbetriebs und ggf. zur Fehlersuche und werden anschlie\u00dfend gel\u00f6scht. Eine Analyse oder Weitergabe an Dritte erfolgt nicht, sofern nicht dazu eine gesetzliche Pflicht besteht.<\/p>\n<h4>2b. Cookies<\/h4>\n<p>Cookies sind kleine Textdateien, die von unserem Webserver \u00fcber Ihren Webbrowser auf Ihrem Computer abgelegt werden. Sie sind erforderlich f\u00fcr die Darstellung der Webseiten und speichern tempor\u00e4r Daten, die der Webserver ben\u00f6tigt, falls Sie sich z.B. online f\u00fcr ein Training anmelden oder eine Reservierung vornehmen wollen.<\/p>\n<p>Wenn Sie das Setzen von Cookies nicht m\u00f6chten, bieten alle \u00fcblichen Browserprogramme entsprechende Einstellungen zur Blockade und L\u00f6schung der Cookies an. Falls Sie Cookies von unserer Website blockieren, sind jedoch nicht mehr alle Funktionen verf\u00fcgbar.<\/p>\n<p>Laden &amp; installieren Sie das unter dem folgenden Link verf\u00fcgbare Browser-Add-on zur Deaktivierung von Google Analytics:<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noopener\"><br \/>https:\/\/tools.google.com\/dlpage\/gaoptout<\/a><\/p>\n<p><strong>Allgemeine Datenschutzhinweise von Google<\/strong><\/p>\n<p>Ausf\u00fchrliche Details finden Sie im Datenschutz-Center von google.de:<br \/><a title=\"Transparenz und Wahlm\u00f6glichkeiten\" href=\"https:\/\/policies.google.com\/\" target=\"_blank\" rel=\"noopener\">Transparenz und Wahlm\u00f6glichkeiten sowie Datenschutzbestimmungen<\/a><\/p>\n<h4>2d. CleverReach<\/h4>\n<p>Die CleverReach GmbH &amp; Co. KG f\u00fchrt in unserem Auftrag Erhebungen \u00fcber die Nutzung unserer Newsletter durch, z.B. ob, wann und wie oft unser Newsletter und spezielle Inhalte gelesen werden, auf welchen Endger\u00e4ten und mit welcher Software. Diese Informationen lassen sich technisch zwar den Empf\u00e4ngern zuordnen; es ist jedoch weder unser Bestreben noch das von CleverReach, einzelne Nutzer zu beobachten. Die Auswertungen dienen uns vielmehr dazu, Lesegewohnheiten zu erkennen und unsere Inhalte anzupassen bzw. unterschiedliche Inhalte entsprechend der Interessen zu versenden. Dar\u00fcber hinaus erstellt CleverReach Statistiken \u00fcber die An- und Abmeldungen vom Newsletter sowie Informationen \u00fcber nicht mehr existierende Mailadressen. Mehr \u00fcber den Datenschutz bei CleverReach finden Sie hier:<\/p>\n<ul>\n<li><a title=\"Datenschutz\" href=\"https:\/\/www.cleverreach.com\/de\/datensicherheit\/\" target=\"_blank\" rel=\"noopener\">Datensicherheit\u00a0<\/a><\/li>\n<li><a title=\"Datenschutz\" href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener\">Datenschutz\u00a0<\/a><\/li>\n<\/ul>\n<h3>3. Kontaktaufnahme<\/h3>\n<p><span>Sie treten mit uns auf verschiedenste Arten in Kontakt. Sie nutzen Kontaktformulare auf unserer Website, rufen uns an, fordern Angebote an, bitten um Gespr\u00e4chstermine, reservieren oder buchen Pl\u00e4tze in Trainings, bestellen Newsletter, bitten um technische Unterst\u00fctzung uns so weiter. In allen F\u00e4llen \u00fcbermitteln Sie uns personenbezogene Daten.<\/span><\/p>\n<h4>3a. Kontaktformular<\/h4>\n<p>Die von Ihnen angegeben Kontaktdaten werden uns von unseren Webservern in Form einer E-Mail \u00fcbermittelt. Diese wird wie im gesch\u00e4ftlichen E-Mail-Verkehr vorgeschrieben gespeichert und f\u00fcr die gesetzlich vorgeschriebene Zeit archiviert.<\/p>\n<h4>3b. Newsletter<\/h4>\n<p>Die Anmeldung erfolgt i.d.R. in einem sog. Double-Opt-In-Verfahren, bei dem Sie nach dem Absenden des Online-Anmeldeformulars mit Ihren Kontaktdaten eine E-Mail zur aktiven Best\u00e4tigung Ihrer Anmeldung erhalten. So wird ein Missbrauch von Mailadressen ausgeschlossen. Alle Anmeldungen zum Newsletter werden protokolliert, um einen Nachweis entsprechend der rechtlichen Anforderungen erbringen zu k\u00f6nnen (Anmelde-\/Best\u00e4tigungszeitpunkt, genutzte IP-Adresse\/n). Dar\u00fcber hinaus sind auch andere Anmeldem\u00f6glichkeiten vorgesehen.<\/p>\n<p>Der Versand unseres Newsletters erfolgt in unserem Auftrag \u00fcber den deutschen Anbieter CleverReach GmbH &amp; Co. KG, M\u00fchlenstra\u00dfe 43, 26180 Rastede. Die Mailadressen unserer Newsletter-Empf\u00e4nger sowie weitere im Rahmen dieses Absatzes beschriebenen Daten werden in CleverReach-Rechenzentren ausschlie\u00dflich im europ\u00e4ischen Raum gespeichert. CleverReach verwendet diese Daten nur zum Versand und zur Auswertung des Newsletters.<\/p>\n<p>U.U. erg\u00e4nzen wir die bei CleverReach gespeicherten Informationen (Name, E-Mail-Adresse, Firma) noch um einzelne Daten, wie z.B. Ihre Interessengebiete. Diese Daten nutzen wir ausschlie\u00dflich, um die Inhalte des Newsletters Ihren Interessen anzupassen.<\/p>\n<h4>3c. Angebotsanfrage, Reservierung, Bestellung, Auftragsabwicklung<\/h4>\n<p>Die von Ihnen angegeben Kontaktdaten werden uns von unseren Webservern in Form einer E-Mail \u00fcbermittelt. Diese wird &#8211; wie im gesch\u00e4ftlichen E-Mail-Verkehr vorgeschrieben &#8211; gespeichert und f\u00fcr die gesetzlich vorgeschriebene Zeit archiviert.<\/p>\n<h3>4. Zwecke und Rechtsgrundlagen f\u00fcr die Verarbeitung personenbezogener Daten<\/h3>\n<p>Es ist ein Teil unseres Dienstleistungsangebots, dass wir personenbezogene Daten von Ihnen verarbeiten, um kundenorientierte Services anbieten zu k\u00f6nnen. Wir verarbeiten Ihre Daten zu den im Folgenden aufgef\u00fchrten Zwecken auf der im Einzelnen genannten Rechtsgrundlage:<\/p>\n<p>F\u00fcr einige Verarbeitungszwecke ben\u00f6tigen wir Ihre Einwilligung, die wir dann von Ihnen gesondert an entsprechender Stelle einholen. In diesen F\u00e4llen erfolgt die Verarbeitung Ihrer Daten auf der Rechtsgrundlage des Art. 6 Abs. 1 Buchst. a DSGVO. Dies ist z.B. der Fall, wenn wir w\u00e4hrend einer\u00a0 Veranstaltung f\u00fcr die Bereitstellung spezieller Services Ihre Einwilligung erbeten. Melden Sie sich f\u00fcr eine kostenlose Weiterbildungsveranstaltung, z.B. ein kostenloses Webinar, an, erfolgt die Datenverarbeitung ggf. in Form einer Kontaktdaten-Weitergabe an den\/die im Buchungsformular aufgef\u00fchrten Kooperationspartner ebenfalls auf Basis Ihrer Einwilligung. Informationen zur weiteren Verarbeitung durch unsere Kooperationspartner finden Sie in der ma\u00dfgeblichen Einwilligungserkl\u00e4rung im Buchungsformular und in den Datenschutzbestimmungen des jeweiligen Kooperationspartners.<\/p>\n<p>Ihre Einwilligung k\u00f6nnen Sie jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen. Informationen hierzu k\u00f6nnen Sie dem Abschnitt &#8222;Ihre Rechte&#8220; entnehmen.<\/p>\n<p>Wenn ein Vertrag zwischen Ihnen und uns zustande kommt, verarbeiten wir Ihre Daten zur Erf\u00fcllung dieses Vertrages auf Grundlage des Art. 6 Abs. 1 Buchst. b DSGVO. Dies ist insbesondere zu folgenden Zwecken erforderlich:<\/p>\n<ul>\n<li>Anmeldung zu einer Schulung\/Weiterbildungsveranstaltung. In diesem Fall verarbeiten wir Ihre personenbezogenen Daten, um die Teilnehmenden der Weiterbildungsveranstaltung bei der Planung, Anmeldung, Teilnahme und Nachbereitung zu betreuen und zu unterst\u00fctzen, und versorgen Sie mit allen notwendigen und n\u00fctzlichen Informationen.<\/li>\n<li>Weitergabe Ihrer Daten an Kooperationspartner bei Inanspruchnahme unentgeltlicher Services auf Grundlage der Gesch\u00e4ftspraxis, der Sie in den AGB zugestimmt haben.<\/li>\n<li>Abwicklung und Fakturierung Ihrer kostenpflichtigen Anmeldung zur Weiterbildungsveranstaltung.<\/li>\n<\/ul>\n<p>Grundlage der Verarbeitung ist in anderen als den vorgenannten F\u00e4llen das Erfordernis zur Wahrung unserer berechtigten Interessen nach Art. 6 Abs. 1 Buchst. f DSGVO, insbesondere kundenorientierte Services anzubieten sowie gleiche und \u00e4hnliche Produkte aus unserem Produktportfolio zu bewerben. Die Verarbeitung erfolgt in diesen F\u00e4llen zu folgenden Zwecken:<\/p>\n<ul>\n<li>Bedarfsgerechte Gestaltung unseres Angebots<\/li>\n<li>Kontaktaufnahme zur Veranstaltungswerbung<\/li>\n<li>Werbeansprache per E-Mail und Newsletter zur Bewerbung \u00e4hnlicher Dienstleistungen, wenn wir Ihre E-Mail-Adresse im Rahmen der Buchung einer kostenpflichtigen oder kostenfreien Dienstleistung von Ihnen erhalten haben (vgl. \u00a7\u00a07 Abs.\u00a03 Gesetz gegen den unlauteren Wettbewerb (UWG))<\/li>\n<li>Gew\u00e4hrleistung der Sicherheit eigener IT-Systeme sowie Optimierung und Funktionsf\u00e4higkeit unserer Webseiten durch Protokollierung technischer Nutzungsdaten in Logfiles<\/li>\n<\/ul>\n<p>Erfolgt die Verarbeitung auf Grundlage unserer berechtigten Interessen, steht Ihnen diesbez\u00fcglich grunds\u00e4tzlich ein Widerspruchsrecht zu (siehe Abschnitt Ihre Rechte). Kein Widerspruchsrecht besteht f\u00fcr die F\u00e4lle der Erfassung technischer Nutzungsdaten zur Bereitstellung unserer Webseiten und der Speicherung dieser Daten in Logfiles zu den in diesem Abschnitt aufgef\u00fchrten Zwecken.<\/p>\n<section id=\"main\" style=\"padding-top: 20px;\">\n<div class=\"wrapper\">\n<article>\n<div class=\"contentpage clearfix\">\n<div class=\"contentFliesstext\">\n<h3>5. Art der Daten<\/h3>\n<p>Grunds\u00e4tzlich erbitten, verarbeiten und speichern wir nur personenbezogene Daten, die zur Erf\u00fcllung Ihres Wunsches sinnvoll bzw. f\u00fcr die Auftragserf\u00fcllung notwendig sind:<\/p>\n<ul>\n<li>Namen, Vornamen, Anreden, E-Mail-Adressen, auch von Kontaktpersonen in Ihrer Firma<\/li>\n<li>Name und Adresse der Firma, in deren Namen Sie uns kontaktieren,<br \/>ggf. Abteilungsbezeichnung\u00a0und Job Position<\/li>\n<li>Telefon- bzw. Faxnummern innerhalb der Firma<\/li>\n<li>besuchte\u00a0Weiterbildungsveranstaltungen<\/li>\n<\/ul>\n<h3>6. Speicherort<\/h3>\n<p>\u00dcblicherweise verarbeiten und speichern wir alle personenbezogenen Daten im eigenen Hause. Nur in Ausnahmef\u00e4llen \u00fcbermitteln wir personenbezogene Daten an Dritte, und zwar an:<\/p>\n<ul>\n<li>\u00f6ffentliche Stellen aufgrund gesetzlicher Vorgaben<\/li>\n<li>Auftragsverarbeiter im Sinne des Artikels 28 DSGVO im Rahmen unserer Auftr\u00e4ge<\/li>\n<\/ul>\n<h3>7. Weitergabe personenbezogener Daten<\/h3>\n<p>Eine Weitergabe personenbezogener Daten &#8211; gleich zu welchem Zweck &#8211; in L\u00e4nder au\u00dferhalb der Europ\u00e4ischen Union bzw. des Europ\u00e4ischen Wirtschaftsraumes erfolgt nicht.<\/p>\n<h3>8. Sicherheit der Daten\u00fcbertragung und -speicherung<\/h3>\n<p>Wir weisen Sie darauf hin, dass die Daten\u00fcbertragung im Internet Sicherheitsl\u00fccken aufweisen kann \u2013 auch wenn unsere Website mit SSL-Verschl\u00fcsselung arbeitet, wie Sie an der Adresse mit &#8222;https:&#8220; und dem Schloss-Symbol feststellen k\u00f6nnen. Auch bei der \u00dcbertragung Ihrer Daten in E-Mails stellen wir die Verschl\u00fcsselung mit SSL und aktuellen Verschl\u00fcsselungsverfahren zur Verf\u00fcgung. Dennoch empfehlen wir f\u00fcr kritische Informationen zus\u00e4tzliche Verschl\u00fcsselungen bzw. den Postversand.<\/p>\n<p>Zum Schutz der von uns gespeicherten pers\u00f6nlichen Daten gegen zuf\u00e4llige bzw. vors\u00e4tzliche Manipulationen, Verlust, Zerst\u00f6rung oder vor dem Zugriff unberechtigter Personen setzen wir technische und organisatorische Sicherheitsma\u00dfnahmen ein, die kontinuierlich \u00fcberpr\u00fcft und entsprechend dem Stand der Technik verbessert werden.<\/p>\n<p>Die von uns verwendeten Hard- und Softwaresysteme sind nur mittels Zugangsberechtigung nutzbar. Innerhalb der Anwendungen sind die Benutzerrechte nach Aufgabengebiet und gesch\u00e4ftlichem Bedarf weiter \u00fcber entsprechende Berechtigungssysteme eingeschr\u00e4nkt.<\/p>\n<h3>9. Dauer der Speicherung personenbezogener Daten<\/h3>\n<p>Personenbezogene Daten werden von uns nur so lange aufbewahrt, wie es zur Erf\u00fcllung Ihrer W\u00fcnsche und Auftr\u00e4ge an uns erforderlich bzw. es in gesetzlich vorgegebenen Aufbewahrungsfristen gefordert ist.<\/p>\n<h3>10. Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h3>\n<p>Die Artikel 15 bis 21 der Datenschutz-Grundverordnung geben Ihnen umfassende Rechte:<\/p>\n<ul>\n<li>Recht auf Auskunft<\/li>\n<li>Recht auf Berichtigung<\/li>\n<li>Recht auf L\u00f6schung, soweit der Gesetzgeber nicht bestimmte Aufbewahrungsfristen vorschreibt<\/li>\n<li>Recht auf Einschr\u00e4nkung der Verarbeitung<\/li>\n<li>Recht auf Daten\u00fcbertragbarkeit<\/li>\n<li>Widerspruchsrecht gegen die Verarbeitung<\/li>\n<\/ul>\n<p>Sofern Sie von Ihren Rechten Gebrauch machen wollen, wenden Sie sich bitte per Briefpost an die o.g. Adresse oder per E-Mail an<span>\u00a0<\/span><a title=\"Mail\" href=\"mailto:datenschutz@microconsult.com\" target=\"_blank\" rel=\"noopener\">datenschutz@microconsult.com<\/a>.<\/p>\n<p>Dar\u00fcber hinaus haben Sie nach Artikel 77 DSGVO das Recht auf Beschwerde bei einer zust\u00e4ndigen Aufsichtsbeh\u00f6rde.<\/p>\n<h3>11. Fragen<\/h3>\n<p>Mit allen Fragen und Anregungen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter\u00a0<a title=\"Mail\" href=\"mailto:datenschutz@microconsult.com\" target=\"_blank\" rel=\"noopener\">datenschutz@microconsult.com<\/a><span>\u00a0<\/span>oder der oben angegebenen Adresse an uns wenden.<\/p>\n<h3>12. \u00c4nderungen und Erg\u00e4nzungen<\/h3>\n<p>\u00c4nderungen der gesetzlichen Vorgaben und Ver\u00e4nderungen unserer Angebote an Sie machen es n\u00f6tig, diese Datenschutzrichtlinien von Zeit zu Zeit anzupassen. Die jeweils aktuelle Fassung finden Sie jeweils<span>\u00a0<\/span><a title=\"MicroConsult Home\" href=\"https:\/\/www.microconsult.de\/\">auf unserer Website<\/a>.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<h3>Besondere Hinweise zur Nutzung unserer Newsletter<\/h3>\n<p>Mit den folgenden Hinweisen informieren wir Sie \u00fcber die Inhalte unseres Newsletters, das Anmelde-, Versand- und statistische Auswerteverfahren sowie Ihre Widerspruchsrechte. Indem Sie unseren Newsletter abonnieren, erkl\u00e4ren Sie sich mit dem Empfang und den hier beschriebenen Verfahren einverstanden.<\/p>\n<h4>Inhalt unserer Newsletter<\/h4>\n<p>Die MicroConsult Academy versendet mehrmals j\u00e4hrlich Newsletter, E-Mails und andere elektronische Benachrichtigungen mit technischen und werblichen Informationen. Generell enthalten unsere Newsletter Informationen zum Thema Embedded Systems Engineering, mit Hinweisen auf relevante Fachinformationen, Trainings und andere Leistungen.<\/p>\n<h4>Sichere Anmeldung\u00a0<strong>\u00fcber das Online-Newsletterformular<\/strong>, Double-Opt-In und Protokollierung<\/h4>\n<p>Die Anmeldung erfolgt in einem sog. Double-Opt-In-Verfahren, bei dem Sie nach dem Absenden des Online-Newsletterformulars eine E-Mail zur aktiven Best\u00e4tigung Ihrer Anmeldung erhalten. So wird ein Missbrauch von Mailadressen ausgeschlossen. Alle Anmeldungen\u00a0zum Newsletter werden protokolliert, um einen Nachweis entsprechend der rechtlichen Anforderungen erbringen zu k\u00f6nnen (Anmelde-\/Best\u00e4tigungszeitpunkt, genutzte IP-Adresse\/n).\u00a0Dar\u00fcber hinaus sind auch andere Anmeldem\u00f6glichkeiten vorgesehen.<\/p>\n<h4>Einsatz des Versanddienstleisters CleverReach<\/h4>\n<p>Der Versand unseres Newsletters erfolgt in unserem Auftrag \u00fcber den deutschen Anbieter CleverReach GmbH &amp; Co. KG, M\u00fchlenstra\u00dfe 43, 26180 Rastede. Die Mailadressen unserer Newsletter-Empf\u00e4nger sowie weitere im Rahmen dieser Hinweise beschriebenen Daten werden in CleverReach-Rechenzentren ausschlie\u00dflich im europ\u00e4ischen Raum gespeichert. CleverReach verwendet diese Daten nur zum Versand und zur Auswertung des Newsletters.<\/p>\n<p>Die CleverReach-Rechenzentren gew\u00e4hrleisten durch ein T\u00dcV-gepr\u00fcftes Informationssicherheits-Managementsystem die Einhaltung des Datenschutzes. Sie sind nach DIN ISO\/IEC 27001 zertifiziert und f\u00fcr den Datensicherheitsstandard der Kreditkartenbranche (DSS\/PCI) als Level 1 Service-Anbieter best\u00e4tigt. Weitere Informationen und Datenschutzbestimmungen finden Sie hier:<\/p>\n<ul>\n<li><a title=\"Datenschutz\" href=\"https:\/\/www.cleverreach.com\/de\/datensicherheit\/\" target=\"_blank\" rel=\"noopener\">Datensicherheit\u00a0<\/a><\/li>\n<li><a title=\"Datenschutz\" href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener\">Datenschutz<\/a><a title=\"Datenschutz\" href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener\"><br \/><\/a><\/li>\n<\/ul>\n<h4>Anmeldedaten<\/h4>\n<p>U.U. werden wir die bei CleverReach gespeicherten Informationen (Name, E-Mail-Adresse, Firma) noch um einzelne Daten erweitern (z.B. Interessengebiete). Diese Daten nutzen wir nur, um die Inhalte des Newsletters Ihren Interessen anzupassen.<\/p>\n<h4>Statistische Erhebung und Analysen<\/h4>\n<p>CleverReach wird in unserem Auftrag Erhebungen \u00fcber die Newsletter-Nutzung durchf\u00fchren, z.B. ob, wann und wie oft unser Newsletter und spezielle Inhalte gelesen werden, auf welchen Endger\u00e4ten und mit welcher Software. Diese Informationen lassen sich technisch zwar den Empf\u00e4ngern zuordnen, doch ist es weder unser Bestreben noch das von CleverReach, einzelne Nutzer zu beobachten. Die Auswertungen dienen uns vielmehr dazu, Lesegewohnheiten zu erkennen und unsere Inhalte anzupassen bzw. unterschiedliche Inhalte entsprechend der Interessen zu versenden. Dar\u00fcber hinaus erstellt CleverReach Statistiken \u00fcber die An- und Abmeldungen vom Newsletter sowie Informationen \u00fcber nicht mehr existierender E-Mail-Adressen.<\/p>\n<h4>Widerruf Ihrer Einwilligung \/ K\u00fcndigung des Newsletter-Bezugs<\/h4>\n<p>Sie k\u00f6nnen sich jederzeit \u00fcber den Abmelde-Link im Newsletter oder \u00fcber das<span>\u00a0<\/span><a title=\"Abmeldung Newsletter\" href=\"https:\/\/www.microconsult.de\/newsletter-embedded-news-von-microconsult\/?newsletter-abmeldung=true\" target=\"_blank\" rel=\"noopener\">Abmeldeformular<span>\u00a0<\/span><\/a>vom Bezug unseres Newsletters abmelden.<\/p>\n<p><em>Stand: 12. August 2025<\/em><\/p>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/section>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DatenschutzDatenschutzerkl\u00e4rung der MicroConsult Academy GmbH Der Schutz Ihrer personenbezogenen Daten, die von uns beim Besuch unserer Webseite, unserer Trainings oder bei der Nutzung unseres Newsletters erhoben, verarbeitet und gespeichert werden, ist uns schon immer ein besonderes Anliegen. 1. Verantwortlich f\u00fcr Datenerfassung, -verarbeitung und -speicherung MicroConsult Academy GmbHCharles-de-Gaulle-Str. 681737 M\u00fcnchenTel.: 089 45061-71Fax: 089 450617-17Email: kontakt@microconsult.com 2. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-5457","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz | MicroConsult Academy GmbH<\/title>\n<meta name=\"description\" content=\"Datenschutzerkl\u00e4rung der MicroConsult Academy GmbH: Infos zu Datenerhebung, Verarbeitung, Speicherung und Ihren Rechten nach DSGVO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.microconsult.de\/en\/data-protection\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz | MicroConsult Academy GmbH\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung der MicroConsult Academy GmbH: Infos zu Datenerhebung, Verarbeitung, Speicherung und Ihren Rechten nach DSGVO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.microconsult.de\/en\/data-protection\/\" \/>\n<meta property=\"og:site_name\" content=\"MicroConsult Academy GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T06:25:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.microconsult.de\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/www.microconsult.de\\\/datenschutz\\\/\",\"name\":\"Datenschutz | MicroConsult Academy GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.microconsult.de\\\/#website\"},\"datePublished\":\"2025-09-24T07:02:15+00:00\",\"dateModified\":\"2026-06-17T06:25:37+00:00\",\"description\":\"Datenschutzerkl\u00e4rung der MicroConsult Academy GmbH: Infos zu Datenerhebung, Verarbeitung, Speicherung und Ihren Rechten nach DSGVO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.microconsult.de\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.microconsult.de\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.microconsult.de\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.microconsult.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.microconsult.de\\\/#website\",\"url\":\"https:\\\/\\\/www.microconsult.de\\\/\",\"name\":\"MicroConsult Academy GmbH\",\"description\":\"Professionelle Schulungen, Beratung und Projektunterst\u00fctzung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.microconsult.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Data protection | MicroConsult Academy GmbH","description":"Privacy policy of MicroConsult Academy GmbH: Information on data collection, processing, storage and your rights under the GDPR.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.microconsult.de\/en\/data-protection\/","og_locale":"en_GB","og_type":"article","og_title":"Datenschutz | MicroConsult Academy GmbH","og_description":"Datenschutzerkl\u00e4rung der MicroConsult Academy GmbH: Infos zu Datenerhebung, Verarbeitung, Speicherung und Ihren Rechten nach DSGVO.","og_url":"https:\/\/www.microconsult.de\/en\/data-protection\/","og_site_name":"MicroConsult Academy GmbH","article_modified_time":"2026-06-17T06:25:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.microconsult.de\/datenschutz\/","url":"https:\/\/www.microconsult.de\/datenschutz\/","name":"Data protection | MicroConsult Academy GmbH","isPartOf":{"@id":"https:\/\/www.microconsult.de\/#website"},"datePublished":"2025-09-24T07:02:15+00:00","dateModified":"2026-06-17T06:25:37+00:00","description":"Privacy policy of MicroConsult Academy GmbH: Information on data collection, processing, storage and your rights under the GDPR.","breadcrumb":{"@id":"https:\/\/www.microconsult.de\/datenschutz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.microconsult.de\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.microconsult.de\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.microconsult.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.microconsult.de\/#website","url":"https:\/\/www.microconsult.de\/","name":"MicroConsult Academy GmbH","description":"Professional training, consulting and project support","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.microconsult.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/pages\/5457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/comments?post=5457"}],"version-history":[{"count":19,"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/pages\/5457\/revisions"}],"predecessor-version":[{"id":12793,"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/pages\/5457\/revisions\/12793"}],"wp:attachment":[{"href":"https:\/\/www.microconsult.de\/en\/wp-json\/wp\/v2\/media?parent=5457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}